{"id":26,"date":"2023-12-07T12:55:41","date_gmt":"2023-12-07T12:55:41","guid":{"rendered":"https:\/\/web4.rkinformatika.net\/clinicasanzbarbadillo\/?page_id=26"},"modified":"2023-12-15T09:09:53","modified_gmt":"2023-12-15T09:09:53","slug":"accesibilidad","status":"publish","type":"page","link":"https:\/\/clinicasanzbarbadillo.com\/eu\/accesibilidad\/","title":{"rendered":"Irisgarritasuna"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"26\" class=\"elementor elementor-26\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-381bb86 e-flex e-con-boxed e-con e-parent\" data-id=\"381bb86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6db5aab0 elementor-widget elementor-widget-text-editor\" data-id=\"6db5aab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h1 class=\"western\"><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: x-large;\"><b>ACCESIBILIDAD<\/b><\/span><\/span><\/span><\/h1>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\"><b>Sanz Barbadillo-ren klinika<\/b><\/span><\/span><\/span><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">\u00a0se ha comprometido a hacer accesible su sitio web, de conformidad con el\u00a0<\/span><\/span><\/span><a href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2018-12699\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Real Decreto 1112\/2018, de 7 de septiembre, sobre accesibilidad de los sitios web y aplicaciones para dispositivos m\u00f3viles del sector p\u00fablico.<\/span><\/span><\/span><\/a><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">La presente declaraci\u00f3n de accesibilidad se aplica al sitio web <b>https:\/\/clinicasanzbarbadillo.com<\/b><\/span><\/span><\/span><\/p>\n<h2 class=\"western\"><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\">Situaci\u00f3n de cumplimiento<\/span><\/span><\/h2>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Este sitio web es parcialmente conforme con el\u00a0<\/span><\/span><\/span><a href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2018-12699\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">RD 1112\/2018<\/span><\/span><\/span><\/a><span style=\"color: #ff0000;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\"><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\">Preparaci\u00f3n para la siguiente declaraci\u00f3n de accesibilidad<\/span><\/span><\/h2>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">La presente declaraci\u00f3n fue preparada el <b>15<\/b><b> de Diciembre<\/b><b>\u00a0de 2023.<\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">El m\u00e9todo empleado para preparar la declaraci\u00f3n ha sido una autoevaluaci\u00f3n llevada a cabo por el propio organismo.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Observaciones y datos de contacto<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Puede realizar comunicaciones sobre requisitos de accesibilidad (art\u00edculo 10.2.a del RD 1112\/2018) como, por ejemplo:<\/span><\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Informar sobre cualquier posible incumplimiento por parte de este sitio web<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Transmitir otras dificultades de acceso al contenido<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Formular cualquier otra consulta o sugerencia de mejora relativa a la accesibilidad del sitio web<\/span><\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">a trav\u00e9s del formulario de contacto de este sitio web o a trav\u00e9s del n\u00famero de tel\u00e9fono (+34) <strong>944 386 725.<\/strong><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Puede presentar:<\/span><\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Queja relativa al cumplimiento de los requisitos del RD 1112\/2018 o<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Solicitud de Informaci\u00f3n accesible relativa a:<\/span><\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Contenidos que est\u00e1n excluidos del \u00e1mbito de aplicaci\u00f3n del RD 1112\/2018 seg\u00fan lo establecido por el art\u00edculo 3, apartado 4<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Contenidos que est\u00e1n exentos del cumplimiento de los requisitos de accesibilidad por imponer una carga desproporcionada<\/span><\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">En la Solicitud de informaci\u00f3n accesible, se debe concretar, con toda claridad, los hechos, razones y petici\u00f3n que permitan constatar que se trata de una solicitud razonable y leg\u00edtima.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Las quejas y reclamaciones sobre informaci\u00f3n accesible se realizar\u00e1n a trav\u00e9s de la sede electr\u00f3nica (<b>https:\/\/clinicasanzbarbadillo.com<\/b><b>\/contacto\/<\/b>), y ser\u00e1n recibidas y tratadas por el \u00e1rea de Sistemas de la Informaci\u00f3n de <b>Sanz Barbadillo-ren klinika<\/b>.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\"><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\">Contenido opcional<\/span><\/span><\/h2>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Este portal est\u00e1 dise\u00f1ado para poder cambiar el tama\u00f1o del texto y el color, as\u00ed como el fondo de la p\u00e1gina mediante las opciones de configuraci\u00f3n est\u00e1ndar de los navegadores.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Si desea cambiar el tama\u00f1o de letra del texto en los principales navegadores gr\u00e1ficos utilice los siguientes men\u00fas:<\/span><\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Internet Explorer, Mozilla y Firefox: Ver &gt; Tama\u00f1o del texto<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Opera: Ver &gt; Zoom<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Safari: Ver &gt; Hacer el texto m\u00e1s grande<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Chrome: Controla la p\u00e1gina actual &gt; Tama\u00f1o del texto<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Para modificar el tama\u00f1o de todo en la p\u00e1gina:<\/span><\/span><\/span><\/p>\n<ul>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Ctrl + + para aumentarlo<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Ctrl + \u2013 para disminuirlo<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Ctrl + 0 restaura el tama\u00f1o original del texto<\/span><\/span><\/span><\/p>\n<\/li>\n<li>\n<p><span style=\"color: #666666;\"><span style=\"font-family: Helvetica 65 Medium, sans-serif;\"><span style=\"font-size: medium;\">Si lo que quiere es anular la hoja de estilos o modificar el color del texto, puede consultar la p\u00e1gina\u00a0<span lang=\"en-US\">How to Change Text Size or Colors de la WAI<\/span>, que se puede leer traducida al espa\u00f1ol en \u00bfC\u00f3mo cambiar el tama\u00f1o del texto o colores?<\/span><\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ACCESIBILIDAD Cl\u00ednica Sanz Barbadillo\u00a0se ha comprometido a hacer accesible su sitio web, de conformidad con el\u00a0Real Decreto 1112\/2018, de 7 de septiembre, sobre accesibilidad de los sitios web y aplicaciones para dispositivos m\u00f3viles del sector p\u00fablico. La presente declaraci\u00f3n de accesibilidad se aplica al sitio web https:\/\/clinicasanzbarbadillo.com Situaci\u00f3n de cumplimiento Este sitio web es parcialmente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-26","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accesibilidad - Clinica Sanz Barbadillo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicasanzbarbadillo.com\/eu\/accesibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accesibilidad - Clinica Sanz Barbadillo\" \/>\n<meta property=\"og:description\" content=\"ACCESIBILIDAD Cl\u00ednica Sanz Barbadillo\u00a0se ha comprometido a hacer accesible su sitio web, de conformidad con el\u00a0Real Decreto 1112\/2018, de 7 de septiembre, sobre accesibilidad de los sitios web y aplicaciones para dispositivos m\u00f3viles del sector p\u00fablico. La presente declaraci\u00f3n de accesibilidad se aplica al sitio web https:\/\/clinicasanzbarbadillo.com Situaci\u00f3n de cumplimiento Este sitio web es parcialmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicasanzbarbadillo.com\/eu\/accesibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinica Sanz Barbadillo\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T09:09:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/accesibilidad\\\/\",\"url\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/accesibilidad\\\/\",\"name\":\"Accesibilidad - Clinica Sanz Barbadillo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#website\"},\"datePublished\":\"2023-12-07T12:55:41+00:00\",\"dateModified\":\"2023-12-15T09:09:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/accesibilidad\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/accesibilidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/accesibilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accesibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#website\",\"url\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/\",\"name\":\"Clinica Sanz Barbadillo\",\"description\":\"Centro especializado en el cuidado de la salud visual\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#organization\",\"name\":\"Clinica Sanz Barbadillo\",\"url\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-lOGO_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-lOGO_Mesa-de-trabajo-1.png\",\"width\":933,\"height\":229,\"caption\":\"Clinica Sanz Barbadillo\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicasanzbarbadillo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accesibilidad - Clinica Sanz Barbadillo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicasanzbarbadillo.com\/eu\/accesibilidad\/","og_locale":"en_US","og_type":"article","og_title":"Accesibilidad - Clinica Sanz Barbadillo","og_description":"ACCESIBILIDAD Cl\u00ednica Sanz Barbadillo\u00a0se ha comprometido a hacer accesible su sitio web, de conformidad con el\u00a0Real Decreto 1112\/2018, de 7 de septiembre, sobre accesibilidad de los sitios web y aplicaciones para dispositivos m\u00f3viles del sector p\u00fablico. La presente declaraci\u00f3n de accesibilidad se aplica al sitio web https:\/\/clinicasanzbarbadillo.com Situaci\u00f3n de cumplimiento Este sitio web es parcialmente [&hellip;]","og_url":"https:\/\/clinicasanzbarbadillo.com\/eu\/accesibilidad\/","og_site_name":"Clinica Sanz Barbadillo","article_modified_time":"2023-12-15T09:09:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicasanzbarbadillo.com\/accesibilidad\/","url":"https:\/\/clinicasanzbarbadillo.com\/accesibilidad\/","name":"Accesibilidad - Clinica Sanz Barbadillo","isPartOf":{"@id":"https:\/\/clinicasanzbarbadillo.com\/#website"},"datePublished":"2023-12-07T12:55:41+00:00","dateModified":"2023-12-15T09:09:53+00:00","breadcrumb":{"@id":"https:\/\/clinicasanzbarbadillo.com\/accesibilidad\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicasanzbarbadillo.com\/accesibilidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clinicasanzbarbadillo.com\/accesibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicasanzbarbadillo.com\/"},{"@type":"ListItem","position":2,"name":"Accesibilidad"}]},{"@type":"WebSite","@id":"https:\/\/clinicasanzbarbadillo.com\/#website","url":"https:\/\/clinicasanzbarbadillo.com\/","name":"Clinica Sanz Barbadillo","description":"Centro especializado en el cuidado de la salud visual","publisher":{"@id":"https:\/\/clinicasanzbarbadillo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicasanzbarbadillo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/clinicasanzbarbadillo.com\/#organization","name":"Clinica Sanz Barbadillo","url":"https:\/\/clinicasanzbarbadillo.com\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/clinicasanzbarbadillo.com\/#\/schema\/logo\/image\/","url":"https:\/\/clinicasanzbarbadillo.com\/wp-content\/uploads\/2023\/12\/cropped-lOGO_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/clinicasanzbarbadillo.com\/wp-content\/uploads\/2023\/12\/cropped-lOGO_Mesa-de-trabajo-1.png","width":933,"height":229,"caption":"Clinica Sanz Barbadillo"},"image":{"@id":"https:\/\/clinicasanzbarbadillo.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/pages\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":7,"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":701,"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/pages\/26\/revisions\/701"}],"wp:attachment":[{"href":"https:\/\/clinicasanzbarbadillo.com\/eu\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}